{"id":81441,"date":"2018-11-29T14:46:36","date_gmt":"2018-11-29T05:46:36","guid":{"rendered":"https:\/\/www.sejuku.net\/blog\/?p=81441"},"modified":"2024-05-06T11:53:38","modified_gmt":"2024-05-06T02:53:38","slug":"php%e3%81%ae%e3%82%a8%e3%83%a9%e3%83%bc%e3%83%ad%e3%82%b0%e5%87%ba%e5%8a%9b%e3%81%ae%e3%81%8a%e6%82%a9%e3%81%bf%e3%82%92%e8%a7%a3%e6%b1%ba%ef%bc%81%e7%b0%a1%e5%8d%98%e8%a7%a3%e8%aa%ac%e3%81%a7","status":"publish","type":"post","link":"https:\/\/www.sejuku.net\/blog\/81441","title":{"rendered":"PHP\u306e\u30a8\u30e9\u30fc\u30ed\u30b0\u51fa\u529b\u306e\u304a\u60a9\u307f\u3092\u89e3\u6c7a\uff01\u7c21\u5358\u89e3\u8aac\u3067\u6700\u901f\u7406\u89e3"},"content":{"rendered":"<p>\u30a8\u30e9\u30fc\u30ed\u30b0\u306e\u51fa\u529b\u306f\u958b\u767a\u306e\u4e0a\u3067\u3068\u3066\u3082\u5927\u5207\u3067\u3059\u3002<\/p>\n<p>\u30a8\u30e9\u30fc\u3092\u78ba\u8a8d\u3059\u308b\u4e8b\u3067\u52d5\u4f5c\u3057\u306a\u3044\u539f\u56e0\u7b49\u304c\u5224\u660e\u3059\u308b\u304b\u3089\u3067\u3059\u3002<\/p>\n<p>\u672c\u65e5\u306f\u30a8\u30e9\u30fc\u30ed\u30b0\u306e\u51fa\u529b\u306b\u3064\u3044\u3066\u4ee5\u4e0b\u306e\u5185\u5bb9\u3067\u304a\u8a71\u3057\u3066\u3044\u304d\u307e\u3059\u3002<\/p>\n<p>\u3010\u57fa\u672c\u3011\u30a8\u30e9\u30fc\u30ed\u30b0\u306e\u51fa\u3057\u65b9<br \/>\n\u3010\u89e3\u8aac\u3011\u30a8\u30e9\u30fc\u30ed\u30b0\u304c\u51fa\u529b\u3055\u308c\u306a\u3044\u6642<br \/>\n\u3010\u89e3\u8aac\u3011\u30a8\u30e9\u30fc\u30ed\u30b0\u306e\u51fa\u529b\u5148<\/p>\n<p>\u57fa\u672c\u304b\u3089\u4e01\u5be7\u306b\u89e3\u8aac\u3057\u3066\u3044\u304d\u307e\u3059\u306e\u3067\u3001\u6700\u5f8c\u307e\u3067\u8aad\u3093\u3067\u9802\u3051\u308b\u3068\u5e78\u3044\u3067\u3059\u3002<\/p>\n<h2>\u30a8\u30e9\u30fc\u30ed\u30b0\u306e\u51fa\u3057\u65b9<\/h2>\n<p>\u307e\u305a\u306f\u30a8\u30e9\u30fc\u30ed\u30b0\u3092\u753b\u9762\u306b\u51fa\u3059\u8a2d\u5b9a\u3092\u884c\u3044\u307e\u3057\u3087\u3046\u3002<\/p>\n<p>\u305d\u306e\u305f\u3081\u306b\u8a2d\u5b9a\u3059\u308b\u306e\u306f\u3001\u3010php.ini\u3011\u3067\u3059\u3002<\/p>\n<p>\u30ed\u30fc\u30ab\u30eb\u306bPHP\u306e\u74b0\u5883\u3092\u4f5c\u6210\u3057\u3066\u3044\u308b\u5834\u5408\u3001\u3010php.ini\u3011\u306e\u5834\u6240\u306f\u4ee5\u4e0b\u306e\u3088\u3046\u306a\u5834\u6240\u3067\u3059\u3002<\/p>\n<pre class=\"theme:dark-terminal lang:default decode:true \" >\/\/ Windows\u306e\u5834\u5408\r\nC:xamppphpphp.ini\r\n\r\n\/\/ linux\u7cfbOS\u306e\u5834\u5408\r\n\/etc\/php.ini<\/pre>\n<p>\u203b\u74b0\u5883\u306b\u3088\u3063\u3066\u7570\u306a\u308b\u5834\u5408\u3082\u3042\u308a\u307e\u3059\u3002<\/p>\n<p>\u305d\u308c\u3067\u306f\u3001\u30a8\u30e9\u30fc\u30ed\u30b0\u3092\u753b\u9762\u51fa\u529b\u3059\u308b\u305f\u3081\u306e\u8a2d\u5b9a\u3092\u3057\u307e\u3057\u3087\u3046\u3002<\/p>\n<h3>\u30a8\u30e9\u30fc\u30ed\u30b0\u306e\u753b\u9762\u51fa\u529b\u306eOn\uff0fOff<\/h3>\n<p>\u51fa\u529b\u3059\u308b\u304b\u3092\u5207\u308a\u66ff\u3048\u308b\u306b\u306f\u3001php.ini\u306edisplay_errors\u306e\u8a2d\u5b9a\u3092\u5909\u66f4\u3057\u307e\u3059\u3002<\/p>\n<p>\u30a8\u30e9\u30fc\u30ed\u30b0\u3092\u51fa\u529b\u3059\u308b\u6642<\/p>\n<pre class=\"theme:dark-terminal lang:default decode:true \" >display_errors=On<\/pre>\n<p>\u30a8\u30e9\u30fc\u30ed\u30b0\u3092\u51fa\u529b\u3057\u306a\u3044\u6642<\/p>\n<pre class=\"theme:dark-terminal lang:default decode:true \" >display_errors=Off<\/pre>\n<p>php.ini\u3092\u7de8\u96c6\u30fb\u4fdd\u5b58\u5f8c\u3001Web\u30b5\u30fc\u30d0\u3092\u518d\u8d77\u52d5\u3057\u307e\u3057\u3087\u3046\u3002<\/p>\n<p>\u3053\u308c\u3067\u3001\u30d6\u30e9\u30a6\u30b6\u306a\u3069\u306e\u753b\u9762\u306b\u30a8\u30e9\u30fc\u304c\u51fa\u529b\u3055\u308c\u308b\u3088\u3046\u306b\u306a\u308a\u307e\u3059\u3002<\/p>\n<p>\u305f\u3060\u3057\u3001\u958b\u767a\u304c\u7d42\u4e86\u3057\u30b5\u30fc\u30d3\u30b9\u958b\u59cb\u5f8c\u306fdisplay_errors=On\u306b\u306f\u3057\u306a\u3044\u4e8b\u3092\u304a\u52e7\u3081\u3057\u307e\u3059\u3002<\/p>\n<p>\u306a\u305c\u306a\u3089\u3070\u3001\u4f55\u304b\u30a8\u30e9\u30fc\u304c\u767a\u751f\u3057\u305f\u5834\u5408\u306b\u30e6\u30fc\u30b6\u30fc\u306b\u305d\u306e\u5185\u5bb9\u304c\u898b\u3048\u3066\u3057\u307e\u3046\u304b\u3089\u3067\u3059\u3002<\/p>\n<p>\u30e6\u30fc\u30b6\u30fc\u306b\u6df7\u4e71\u3092\u8d77\u3053\u3055\u306a\u3044\u305f\u3081\u3001\u307e\u305f\u30bb\u30ad\u30e5\u30ea\u30c6\u30a3\u306e\u89b3\u70b9\u304b\u3089\u3082display_errors=Off\u8a2d\u5b9a\u306b\u3057\u307e\u3057\u3087\u3046\u3002<\/p>\n<h3>\u30a8\u30e9\u30fc\u30ed\u30b0\u306e\u51fa\u529b\u30ec\u30d9\u30eb\u306e\u8a2d\u5b9a<\/h3>\n<p>\u30ed\u30b0\u306e\u51fa\u529b\u30ec\u30d9\u30eb\u3092\u5909\u66f4\u3059\u308b\u306b\u306f\u3001php.ini\u306eerror_reporting\u306e\u8a2d\u5b9a\u3092\u5909\u66f4\u3057\u307e\u3059\u3002<\/p>\n<p>\u306a\u305c\u3053\u306e\u8a2d\u5b9a\u3092\u3059\u308b\u306e\u304b\u3068\u8a00\u3044\u307e\u3059\u3068\u3001\u5168\u3066\u3092\u30ed\u30b0\u306b\u51fa\u529b\u3059\u308b\u5fc5\u8981\u304c\u306a\u3044\u5834\u5408\u3082\u5b58\u5728\u3059\u308b\u304b\u3089\u3067\u3059\u3002<\/p>\n<p>\u60c5\u5831\u304c\u591a\u3059\u304e\u308b\u3068\u305d\u306e\u4e2d\u306b\u3042\u308b\u91cd\u5927\u306a\u554f\u984c\u3092\u898b\u9003\u3057\u3066\u3057\u307e\u3046\u4e8b\u3082\u3042\u308b\u3067\u3057\u3087\u3046\u3002<\/p>\n<p>\u4ee5\u4e0b\u306e\u3088\u3046\u306b\u8a18\u8ff0\u3092\u3057\u307e\u3059\u3002<\/p>\n<pre class=\"theme:dark-terminal lang:default decode:true \" >error_reporting=E_ALL &amp; ~E_DEPRECATED<\/pre>\n<p>\u3010~\u3011\u306f\u5426\u5b9a\u306e\u610f\u5473\u3067\u3059\u3002<\/p>\n<p>\u3088\u3063\u3066\u3001E_DEPRECATED\u4ee5\u5916\u306e\u5168\u30a8\u30e9\u30fc\u3092\u51fa\u529b\u3059\u308b\u3068\u3044\u3046\u610f\u5473\u3067\u3059\u3002<\/p>\n<p>php.ini\u3092\u7de8\u96c6\u30fb\u4fdd\u5b58\u5f8c\u3001Web\u30b5\u30fc\u30d0\u3092\u518d\u8d77\u52d5\u3057\u307e\u3057\u3087\u3046\u3002<\/p>\n<p>\u3053\u308c\u3067\u30a8\u30e9\u30fc\u304c\u51fa\u529b\u3055\u308c\u308b\u3088\u3046\u306b\u306a\u308a\u307e\u3057\u305f\u3002<\/p>\n<h2>\u30a8\u30e9\u30fc\u30ed\u30b0\u30d5\u30a1\u30a4\u30eb\u306e\u51fa\u529b\u5148<\/h2>\n<p>\u7d9a\u3044\u3066\u753b\u9762\u306b\u3067\u306f\u306a\u304f\u3001\u30a8\u30e9\u30fc\u30ed\u30b0\u30d5\u30a1\u30a4\u30eb\u3092\u51fa\u529b\u3055\u305b\u308b\u65b9\u6cd5\u3067\u3059\u3002<\/p>\n<p>Web\u30b5\u30fc\u30d0\u306fApache\u3092\u60f3\u5b9a\u3057\u3066\u3044\u307e\u3059\u3002<\/p>\n<h3>\u30a8\u30e9\u30fc\u30ed\u30b0\u30d5\u30a1\u30a4\u30eb<\/h3>\n<p>Web\u30b5\u30fc\u30d0\u306e\u30a8\u30e9\u30fc\u30ed\u30b0\u306fhttpd.conf\u3067\u8a2d\u5b9a\u3057\u307e\u3059\u3002<\/p>\n<pre class=\"theme:dark-terminal lang:default decode:true \" >ErrorLog &quot;logs\/php\/error.log&quot;<\/pre>\n<p>\u51fa\u529b\u3059\u308b\u5834\u6240\u3092\u5909\u66f4\u3057\u305f\u3044\u5834\u5408\u306f\u3001\u4e0a\u8a18\u9805\u76ee\u3092\u4fee\u6b63\u30fb\u4fdd\u5b58\u3092\u3057\u3066Web\u30b5\u30fc\u30d0\u3092\u518d\u8d77\u52d5\u3057\u307e\u3057\u3087\u3046\u3002<\/p>\n<h3>\u30a8\u30e9\u30fc\u30ed\u30b0\u30d5\u30a1\u30a4\u30eb\u51fa\u529b\u30ec\u30d9\u30eb<\/h3>\n<p>\u51fa\u529b\u3059\u308b\u30a8\u30e9\u30fc\u306e\u30ec\u30d9\u30eb\u3092LogLevel\u3067\u8a2d\u5b9a\u51fa\u6765\u307e\u3059\u3002<\/p>\n<pre class=\"theme:dark-terminal lang:default decode:true \" >LogLevel warn<\/pre>\n<p>warn\u306f\u3001\u8b66\u544a\u3088\u308a\u9ad8\u3044\u30ec\u30d9\u30eb\u306e\u30a8\u30e9\u30fc\u3092\u51fa\u529b\u3057\u307e\u3059\u3002<\/p>\n<p>\u8a2d\u5b9a\u51fa\u6765\u308b\u30ec\u30d9\u30eb\u306f\u4ee5\u4e0b\u306e\u7a2e\u985e\u3067\u3059\u3002<\/p>\n\n<table id=\"tablepress-723\" class=\"tablepress tablepress-id-723\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">\u30ec\u30d9\u30eb<\/th><th class=\"column-2\">\u5185\u5bb9<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">emerg<\/td><td class=\"column-2\">\u7dca\u6025\u72b6\u614b\u3001\u52d5\u4f5c\u4e0d\u53ef<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">alert<\/td><td class=\"column-2\">\u3059\u3050\u306b\u5bfe\u5fdc\u3059\u308b\u5fc5\u8981\u304c\u3042\u308b<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">crit<\/td><td class=\"column-2\">\u81f4\u547d\u7684\u306a\u30a8\u30e9\u30fc\u304c\u767a\u751f\u3057\u3066\u3044\u308b<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">error<\/td><td class=\"column-2\">\u30a8\u30e9\u30fc\u304c\u767a\u751f\u3057\u3066\u3044\u308b<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">warn<\/td><td class=\"column-2\">\u8b66\u544a\u30ec\u30d9\u30eb<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">notice<\/td><td class=\"column-2\">\u5c11\u3057\u91cd\u8981\u306a\u60c5\u5831<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">info<\/td><td class=\"column-2\">\u60c5\u5831<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">debug<\/td><td class=\"column-2\">\u30c7\u30d0\u30c3\u30b0<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-723 from cache -->\n<p>\u958b\u767a\u4e2d\u3067\u3042\u308c\u3070\u3001\u4e00\u756a\u4f4e\u3044debug\u8a2d\u5b9a\u3067\u3088\u3044\u3068\u601d\u3044\u307e\u3059\u3002<\/p>\n<p>\u3057\u304b\u3057\u904b\u7528\u304c\u59cb\u307e\u3063\u3066\u304b\u3089\u3042\u307e\u308a\u4f4e\u30ec\u30d9\u30eb\u306e\u30a8\u30e9\u30fc\u3092\u51fa\u3057\u3066\u3044\u308b\u3068\u3001\u5927\u4e8b\u306a\u60c5\u5831\u3092\u898b\u9003\u3059\u53ef\u80fd\u6027\u304c\u3042\u308a\u307e\u3059\u3002<\/p>\n<p>\u9069\u5207\u306a\u30a8\u30e9\u30fc\u30ec\u30d9\u30eb\u3092\u9078\u629e\u3057\u307e\u3057\u3087\u3046\u3002<\/p>\n<h3>\u30c7\u30d5\u30a9\u30eb\u30c8\u30a8\u30e9\u30fc\u30ed\u30b0\u51fa\u529b\u5148<\/h3>\n<p>Windows\u74b0\u5883\u3067\u306eApache\u30a8\u30e9\u30fc\u30ed\u30b0\u306e\u30c7\u30d5\u30a9\u30eb\u30c8\u51fa\u529b\u5148\u306f<\/p>\n<pre class=\"theme:dark-terminal lang:default decode:true \" >logs\/error.log<\/pre>\n<p>\u306b\u306a\u3063\u3066\u3044\u307e\u3057\u305f\u3002<\/p>\n<p>linux\u7cfbOS\u3067\u306f\u3001Apache\u306e\u30c7\u30d5\u30a9\u30eb\u30c8\u51fa\u529b\u5148\u306f<\/p>\n<pre class=\"theme:dark-terminal lang:default decode:true \" >\/var\/log\/httpd\/error_log<\/pre>\n<p>\u306b\u306a\u3063\u3066\u3044\u307e\u3057\u305f\u3002<\/p>\n<p>\u203b\u74b0\u5883\u3084\u30d0\u30fc\u30b8\u30e7\u30f3\u306b\u3088\u3063\u3066\u5909\u308f\u308b\u4e8b\u304c\u3042\u308a\u307e\u3059\u3002<\/p>\n<p>\u30d5\u30a1\u30a4\u30eb\u304c\u5b58\u5728\u3057\u306a\u304b\u3063\u305f\u5834\u5408\u306b\u306f\u81ea\u52d5\u7684\u306b\u4f5c\u6210\u3055\u308c\u307e\u3059\u3002<\/p>\n<h2>\u30a8\u30e9\u30fc\u30ed\u30b0\u30d5\u30a1\u30a4\u30eb\u304c\u51fa\u529b\u3055\u308c\u306a\u3044\u6642<\/h2>\n<p>\u521d\u3081\u3066\u8a2d\u5b9a\u3092\u884c\u3046\u6642\u306f\u3001\u3046\u307e\u304f\u3044\u304b\u306a\u3044\u4e8b\u304c\u591a\u3044\u3082\u306e\u3067\u3059\u3002<\/p>\n<p>\u518d\u5ea6\u3001\u4ee5\u4e0b\u306e\u70b9\u306b\u3064\u3044\u3066\u30c1\u30a7\u30c3\u30af\u3057\u3066\u307f\u3066\u304f\u3060\u3055\u3044\u3002<\/p>\n<h3>Web\u30b5\u30fc\u30d0\u306e\u518d\u8d77\u52d5<\/h3>\n<p>httpd.conf\u3084php.ini\u306e\u8a2d\u5b9a\u30d5\u30a1\u30a4\u30eb\u3092\u7de8\u96c6\u30fb\u4fdd\u5b58\u5f8c\u306fWeb\u30b5\u30fc\u30d0\u306e\u518d\u8d77\u52d5\u304c\u5fc5\u8981\u306b\u306a\u308a\u307e\u3059\u3002<\/p>\n<p>Windows\u3067xampp\u74b0\u5883\u3092\u4f7f\u7528\u3057\u3066\u3044\u308b\u65b9\u306f\u3001Apache\u306e\u9805\u76ee\u3092\u3010Stop\u3011\u5f8c\u306b\u518d\u5ea6\u3010Start\u3011\u3057\u3066\u304f\u3060\u3055\u3044\u3002<\/p>\n<p>linux\u7cfbOS\u306e\u5834\u5408\u306f\u4ee5\u4e0b\u306e\u3088\u3046\u306a\u30b3\u30de\u30f3\u30c9\u3067\u3059\u3002<\/p>\n<pre class=\"theme:dark-terminal lang:default decode:true \" >service httpd restart<\/pre>\n<p>\u203b\u30d0\u30fc\u30b8\u30e7\u30f3\u3084\u4f7f\u3063\u3066\u3044\u308bOS\u306e\u7a2e\u985e\u306b\u3088\u3063\u3066\u30b3\u30de\u30f3\u30c9\u304c\u9055\u3046\u5834\u5408\u304c\u3042\u308a\u307e\u3059\u3002<\/p>\n<h3>\u30a8\u30e9\u30fc\u30ed\u30b0\u30d5\u30a1\u30a4\u30eb\u306e\u5b58\u5728\u3068\u6240\u6709\u6a29<\/h3>\n<p>linux\u7cfbOS\u306e\u5834\u5408\u3001\u66f8\u304d\u8fbc\u3080\u30d5\u30a1\u30a4\u30eb\u304c\u306a\u3044\u5834\u5408\u306b\u30ed\u30b0\u3092\u4f5c\u6210\u3067\u304d\u306a\u3044\u4e8b\u304c\u3042\u308a\u307e\u3057\u305f\u3002<\/p>\n<p>\u305d\u306e\u5834\u5408\u3001\u4ee5\u4e0b\u306e\u30b3\u30de\u30f3\u30c9\u3067\u5bfe\u5fdc\u3057\u307e\u3059\u3002<\/p>\n<pre class=\"theme:dark-terminal lang:default decode:true \" >touch \/var\/log\/httpd\/error_log\/php_error.log\r\nchown apache:apache \/var\/log\/httpd\/error_log\/php_error.log<\/pre>\n<p>touch\u30b3\u30de\u30f3\u30c9\u3067\u3001\u30a8\u30e9\u30fc\u30ed\u30b0\u30d5\u30a1\u30a4\u30eb\u3092\u4f5c\u6210\u3057\u307e\u3059\u3002<\/p>\n<p>chown\u30b3\u30de\u30f3\u30c9\u3067\u3001\u30a8\u30e9\u30fc\u30ed\u30b0\u30d5\u30a1\u30a4\u30eb\u306e\u6240\u6709\u8005\u3092\u8a2d\u5b9a\u3057\u307e\u3059\u3002<\/p>\n<h2>\u307e\u3068\u3081<\/h2>\n<p>\u4eca\u56de\u306fPHP\u306e\u30a8\u30e9\u30fc\u30ed\u30b0\u51fa\u529b\u306b\u3064\u3044\u3066\u89e3\u8aac\u3057\u307e\u3057\u305f\u3002<\/p>\n<p>\u30a8\u30e9\u30fc\u30ed\u30b0\u306f\u958b\u767a\u4e2d\u3001\u3068\u3066\u3082\u5f79\u306b\u7acb\u3064\u5b58\u5728\u3067\u3059\u3002<\/p>\n<p>\u307e\u305f\u3001\u30b5\u30fc\u30d3\u30b9\u958b\u59cb\u3055\u308c\u305f\u5f8c\u3082\u6f5c\u5728\u7684\u306a\u30d0\u30b0\u3084\u554f\u984c\u306e\u767a\u898b\u306b\u5f79\u306b\u7acb\u3061\u307e\u3059\u3002<\/p>\n<p>\u5fc5\u305a\u8a2d\u5b9a\u3092\u3057\u3066\u4f7f\u3044\u3053\u306a\u305b\u308b\u3088\u3046\u306b\u3057\u3066\u304f\u3060\u3055\u3044\u306d\u3002<\/p>\n<p>\u305d\u308c\u3067\u306f\u3001\u307e\u305f\u3002<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u30a8\u30e9\u30fc\u30ed\u30b0\u306e\u51fa\u529b\u306f\u958b\u767a\u306e\u4e0a\u3067\u3068\u3066\u3082\u5927\u5207\u3067\u3059\u3002 \u30a8\u30e9\u30fc\u3092\u78ba\u8a8d\u3059\u308b\u4e8b\u3067\u52d5\u4f5c\u3057\u306a\u3044\u539f\u56e0\u7b49\u304c\u5224\u660e\u3059\u308b\u304b\u3089\u3067\u3059\u3002 \u672c\u65e5\u306f\u30a8\u30e9\u30fc\u30ed\u30b0\u306e\u51fa\u529b\u306b\u3064\u3044\u3066\u4ee5\u4e0b\u306e\u5185\u5bb9\u3067\u304a\u8a71\u3057\u3066\u3044\u304d\u307e\u3059\u3002 \u3010\u57fa\u672c\u3011\u30a8\u30e9\u30fc\u30ed\u30b0\u306e\u51fa\u3057\u65b9 \u3010\u89e3\u8aac\u3011\u30a8\u30e9\u30fc\u30ed\u30b0\u304c\u51fa\u529b\u3055 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":64982,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"swell_btn_cv_data":"","footnotes":""},"categories":[2348],"tags":[],"class_list":["post-81441","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-php-study"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PHP\u306e\u30a8\u30e9\u30fc\u30ed\u30b0\u51fa\u529b\u306e\u304a\u60a9\u307f\u3092\u89e3\u6c7a\uff01\u7c21\u5358\u89e3\u8aac\u3067\u6700\u901f\u7406\u89e3 | \u4f8d\u30a8\u30f3\u30b8\u30cb\u30a2\u30d6\u30ed\u30b0<\/title>\n<meta name=\"description\" content=\"\u3053\u306e\u8a18\u4e8b\u3067\u306f\u300c PHP\u306e\u30a8\u30e9\u30fc\u30ed\u30b0\u51fa\u529b\u306e\u304a\u60a9\u307f\u3092\u89e3\u6c7a\uff01\u7c21\u5358\u89e3\u8aac\u3067\u6700\u901f\u7406\u89e3 \u300d\u306b\u3064\u3044\u3066\u3001\u8ab0\u3067\u3082\u7406\u89e3\u3067\u304d\u308b\u3088\u3046\u306b\u89e3\u8aac\u3057\u307e\u3059\u3002\u3053\u306e\u8a18\u4e8b\u3092\u8aad\u3081\u3070\u3001\u3042\u306a\u305f\u306e\u60a9\u307f\u304c\u89e3\u6c7a\u3059\u308b\u3060\u3051\u3058\u3083\u306a\u304f\u3001\u65b0\u305f\u306a\u6c17\u4ed8\u304d\u3082\u767a\u898b\u3067\u304d\u308b\u3053\u3068\u3067\u3057\u3087\u3046\u3002\u304a\u60a9\u307f\u306e\u65b9\u306f\u305c\u3072\u3054\u4e00\u8aad\u304f\u3060\u3055\u3044\u3002\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sejuku.net\/blog\/81441\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PHP\u306e\u30a8\u30e9\u30fc\u30ed\u30b0\u51fa\u529b\u306e\u304a\u60a9\u307f\u3092\u89e3\u6c7a\uff01\u7c21\u5358\u89e3\u8aac\u3067\u6700\u901f\u7406\u89e3 | \u4f8d\u30a8\u30f3\u30b8\u30cb\u30a2\u30d6\u30ed\u30b0\" \/>\n<meta property=\"og:description\" content=\"\u3053\u306e\u8a18\u4e8b\u3067\u306f\u300c PHP\u306e\u30a8\u30e9\u30fc\u30ed\u30b0\u51fa\u529b\u306e\u304a\u60a9\u307f\u3092\u89e3\u6c7a\uff01\u7c21\u5358\u89e3\u8aac\u3067\u6700\u901f\u7406\u89e3 \u300d\u306b\u3064\u3044\u3066\u3001\u8ab0\u3067\u3082\u7406\u89e3\u3067\u304d\u308b\u3088\u3046\u306b\u89e3\u8aac\u3057\u307e\u3059\u3002\u3053\u306e\u8a18\u4e8b\u3092\u8aad\u3081\u3070\u3001\u3042\u306a\u305f\u306e\u60a9\u307f\u304c\u89e3\u6c7a\u3059\u308b\u3060\u3051\u3058\u3083\u306a\u304f\u3001\u65b0\u305f\u306a\u6c17\u4ed8\u304d\u3082\u767a\u898b\u3067\u304d\u308b\u3053\u3068\u3067\u3057\u3087\u3046\u3002\u304a\u60a9\u307f\u306e\u65b9\u306f\u305c\u3072\u3054\u4e00\u8aad\u304f\u3060\u3055\u3044\u3002\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sejuku.net\/blog\/81441\" \/>\n<meta property=\"og:site_name\" content=\"\u4f8d\u30a8\u30f3\u30b8\u30cb\u30a2\u30d6\u30ed\u30b0\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sejuku2013\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sejuku2013\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-29T05:46:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-06T02:53:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sejuku.net\/blog\/wp-content\/uploads\/2017\/06\/php_eye_new.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u4f8d\u30a8\u30f3\u30b8\u30cb\u30a2\u7de8\u96c6\u90e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/samuraijuku\" \/>\n<meta name=\"twitter:site\" content=\"@samuraijuku\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sejuku.net\\\/blog\\\/81441#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sejuku.net\\\/blog\\\/81441\"},\"author\":{\"name\":\"\u4f8d\u30a8\u30f3\u30b8\u30cb\u30a2\u7de8\u96c6\u90e8\",\"@id\":\"https:\\\/\\\/www.sejuku.net\\\/blog\\\/#\\\/schema\\\/person\\\/e8ca7fd09857a736a25e6b4455a3ab61\"},\"headline\":\"PHP\u306e\u30a8\u30e9\u30fc\u30ed\u30b0\u51fa\u529b\u306e\u304a\u60a9\u307f\u3092\u89e3\u6c7a\uff01\u7c21\u5358\u89e3\u8aac\u3067\u6700\u901f\u7406\u89e3\",\"datePublished\":\"2018-11-29T05:46:36+00:00\",\"dateModified\":\"2024-05-06T02:53:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sejuku.net\\\/blog\\\/81441\"},\"wordCount\":158,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sejuku.net\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sejuku.net\\\/blog\\\/81441#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sejuku.net\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/php_eye_new.jpg\",\"articleSection\":[\"PHP\u5b66\u7fd2\"],\"inLanguage\":\"ja\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sejuku.net\\\/blog\\\/81441\",\"url\":\"https:\\\/\\\/www.sejuku.net\\\/blog\\\/81441\",\"name\":\"PHP\u306e\u30a8\u30e9\u30fc\u30ed\u30b0\u51fa\u529b\u306e\u304a\u60a9\u307f\u3092\u89e3\u6c7a\uff01\u7c21\u5358\u89e3\u8aac\u3067\u6700\u901f\u7406\u89e3 | \u4f8d\u30a8\u30f3\u30b8\u30cb\u30a2\u30d6\u30ed\u30b0\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sejuku.net\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sejuku.net\\\/blog\\\/81441#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sejuku.net\\\/blog\\\/81441#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sejuku.net\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/php_eye_new.jpg\",\"datePublished\":\"2018-11-29T05:46:36+00:00\",\"dateModified\":\"2024-05-06T02:53:38+00:00\",\"description\":\"\u3053\u306e\u8a18\u4e8b\u3067\u306f\u300c PHP\u306e\u30a8\u30e9\u30fc\u30ed\u30b0\u51fa\u529b\u306e\u304a\u60a9\u307f\u3092\u89e3\u6c7a\uff01\u7c21\u5358\u89e3\u8aac\u3067\u6700\u901f\u7406\u89e3 \u300d\u306b\u3064\u3044\u3066\u3001\u8ab0\u3067\u3082\u7406\u89e3\u3067\u304d\u308b\u3088\u3046\u306b\u89e3\u8aac\u3057\u307e\u3059\u3002\u3053\u306e\u8a18\u4e8b\u3092\u8aad\u3081\u3070\u3001\u3042\u306a\u305f\u306e\u60a9\u307f\u304c\u89e3\u6c7a\u3059\u308b\u3060\u3051\u3058\u3083\u306a\u304f\u3001\u65b0\u305f\u306a\u6c17\u4ed8\u304d\u3082\u767a\u898b\u3067\u304d\u308b\u3053\u3068\u3067\u3057\u3087\u3046\u3002\u304a\u60a9\u307f\u306e\u65b9\u306f\u305c\u3072\u3054\u4e00\u8aad\u304f\u3060\u3055\u3044\u3002\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sejuku.net\\\/blog\\\/81441#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sejuku.net\\\/blog\\\/81441\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\\\/\\\/www.sejuku.net\\\/blog\\\/81441#primaryimage\",\"url\":\"https:\\\/\\\/www.sejuku.net\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/php_eye_new.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sejuku.net\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/php_eye_new.jpg\",\"width\":700,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sejuku.net\\\/blog\\\/81441#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.sejuku.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PHP\u306e\u30a8\u30e9\u30fc\u30ed\u30b0\u51fa\u529b\u306e\u304a\u60a9\u307f\u3092\u89e3\u6c7a\uff01\u7c21\u5358\u89e3\u8aac\u3067\u6700\u901f\u7406\u89e3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sejuku.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.sejuku.net\\\/blog\\\/\",\"name\":\"\u4f8d\u30a8\u30f3\u30b8\u30cb\u30a2\u30d6\u30ed\u30b0\",\"description\":\"\u30d7\u30ed\u30b0\u30e9\u30df\u30f3\u30b0\u5b66\u7fd2\u306e\u3059\u3079\u3066\u304c\u30b3\u30b3\u306b\u3002\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sejuku.net\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sejuku.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ja\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sejuku.net\\\/blog\\\/#organization\",\"name\":\"\u682a\u5f0f\u4f1a\u793eSAMURAI\",\"url\":\"https:\\\/\\\/www.sejuku.net\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\\\/\\\/www.sejuku.net\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sejuku.net\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.sejuku.net\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo.png\",\"width\":600,\"height\":600,\"caption\":\"\u682a\u5f0f\u4f1a\u793eSAMURAI\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sejuku.net\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sejuku2013\",\"https:\\\/\\\/x.com\\\/samuraijuku\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCCFOQO5aDK0xXam4cUQXT8g\\\/featured\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sejuku.net\\\/blog\\\/#\\\/schema\\\/person\\\/e8ca7fd09857a736a25e6b4455a3ab61\",\"name\":\"\u4f8d\u30a8\u30f3\u30b8\u30cb\u30a2\u7de8\u96c6\u90e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/507c280c5c67d2c11fec4fdba20e5bf1ec2fe91f9deb42d2ec50382778b311bf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/507c280c5c67d2c11fec4fdba20e5bf1ec2fe91f9deb42d2ec50382778b311bf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/507c280c5c67d2c11fec4fdba20e5bf1ec2fe91f9deb42d2ec50382778b311bf?s=96&d=mm&r=g\",\"caption\":\"\u4f8d\u30a8\u30f3\u30b8\u30cb\u30a2\u7de8\u96c6\u90e8\"},\"description\":\"\u3010\u30d7\u30ed\u30d5\u30a3\u30fc\u30eb\u3011 DX\u8a8d\u5b9a\u53d6\u5f97\u4e8b\u696d\u8005\u306b\u9078\u5b9a\u3055\u308c\u3066\u3044\u308b\u682a\u5f0f\u4f1a\u793eSAMURAI\u306e\u30de\u30fc\u30b1\u30c6\u30a3\u30f3\u30b0\u30fb\u30b3\u30df\u30e5\u30cb\u30b1\u30fc\u30b7\u30e7\u30f3\u90e8\u304c\u904b\u55b6\u3002\u300c\u8cea\u306e\u9ad8\u3044IT\u6559\u80b2\u3092\u3001\u3059\u3079\u3066\u306e\u4eba\u306b\u300d\u3092\u30df\u30c3\u30b7\u30e7\u30f3\u306b\u3001IT\u30fb\u30d7\u30ed\u30b0\u30e9\u30df\u30f3\u30b0\u3092\u5b66\u3073\u59cb\u3081\u305f\u521d\u5b66\u8005\u306e\u65b9\u306b\u5411\u3051\u8a18\u4e8b\u3092\u57f7\u7b46\u3002 \u7d2f\u8a08\u6307\u5c0e\u8005\u65704\u4e075,000\u540d\u4ee5\u4e0a\u306e\u30d7\u30ed\u30b0\u30e9\u30df\u30f3\u30b0\u30b9\u30af\u30fc\u30eb\u300c\u4f8d\u30a8\u30f3\u30b8\u30cb\u30a2\u300d\u3001\u7d2f\u8a08\u767b\u9332\u8005\u65701\u4e078,000\u4eba\u4ee5\u4e0a\u306e\u30aa\u30f3\u30e9\u30a4\u30f3\u5b66\u7fd2\u30b5\u30fc\u30d3\u30b9\u300c\u4f8d\u30c6\u30e9\u30b3\u30e4\u300d\u3067\u6271\u3046\u6559\u6750\u958b\u767a\u306e\u30ce\u30a6\u30cf\u30a6\u30012013\u5e74\u306e\u5275\u696d\u304b\u3089\u904b\u55b6\u3067\u5f97\u305f\u77e5\u898b\u306b\u57fa\u3065\u304d\u3001\u8a18\u4e8b\u306e\u57f7\u7b46\u3060\u3051\u3067\u306a\u304f\u7de8\u96c6\u30fb\u76e3\u4fee\u3082\u62c5\u5f53\u3057\u3066\u3044\u307e\u3059\u3002 \u3010\u5c02\u9580\u5206\u91ce\u3011 IT\\\/Web\u958b\u767a\\\/AI\u30fb\u30ed\u30dc\u30c3\u30c8\u958b\u767a\\\/\u30a4\u30f3\u30d5\u30e9\u958b\u767a\\\/\u30b2\u30fc\u30e0\u958b\u767a\\\/AI\\\/Web\u30c7\u30b6\u30a4\u30f3\",\"sameAs\":[\"https:\\\/\\\/www.sejuku.net\\\/\",\"https:\\\/\\\/www.facebook.com\\\/sejuku2013\\\/\",\"https:\\\/\\\/www.instagram.com\\\/samuraiengineer_official\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/samuraijuku\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCCFOQO5aDK0xXam4cUQXT8g\"],\"url\":\"https:\\\/\\\/www.sejuku.net\\\/blog\\\/author\\\/samurai-blog\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PHP\u306e\u30a8\u30e9\u30fc\u30ed\u30b0\u51fa\u529b\u306e\u304a\u60a9\u307f\u3092\u89e3\u6c7a\uff01\u7c21\u5358\u89e3\u8aac\u3067\u6700\u901f\u7406\u89e3 | \u4f8d\u30a8\u30f3\u30b8\u30cb\u30a2\u30d6\u30ed\u30b0","description":"\u3053\u306e\u8a18\u4e8b\u3067\u306f\u300c PHP\u306e\u30a8\u30e9\u30fc\u30ed\u30b0\u51fa\u529b\u306e\u304a\u60a9\u307f\u3092\u89e3\u6c7a\uff01\u7c21\u5358\u89e3\u8aac\u3067\u6700\u901f\u7406\u89e3 \u300d\u306b\u3064\u3044\u3066\u3001\u8ab0\u3067\u3082\u7406\u89e3\u3067\u304d\u308b\u3088\u3046\u306b\u89e3\u8aac\u3057\u307e\u3059\u3002\u3053\u306e\u8a18\u4e8b\u3092\u8aad\u3081\u3070\u3001\u3042\u306a\u305f\u306e\u60a9\u307f\u304c\u89e3\u6c7a\u3059\u308b\u3060\u3051\u3058\u3083\u306a\u304f\u3001\u65b0\u305f\u306a\u6c17\u4ed8\u304d\u3082\u767a\u898b\u3067\u304d\u308b\u3053\u3068\u3067\u3057\u3087\u3046\u3002\u304a\u60a9\u307f\u306e\u65b9\u306f\u305c\u3072\u3054\u4e00\u8aad\u304f\u3060\u3055\u3044\u3002","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sejuku.net\/blog\/81441","og_locale":"ja_JP","og_type":"article","og_title":"PHP\u306e\u30a8\u30e9\u30fc\u30ed\u30b0\u51fa\u529b\u306e\u304a\u60a9\u307f\u3092\u89e3\u6c7a\uff01\u7c21\u5358\u89e3\u8aac\u3067\u6700\u901f\u7406\u89e3 | \u4f8d\u30a8\u30f3\u30b8\u30cb\u30a2\u30d6\u30ed\u30b0","og_description":"\u3053\u306e\u8a18\u4e8b\u3067\u306f\u300c PHP\u306e\u30a8\u30e9\u30fc\u30ed\u30b0\u51fa\u529b\u306e\u304a\u60a9\u307f\u3092\u89e3\u6c7a\uff01\u7c21\u5358\u89e3\u8aac\u3067\u6700\u901f\u7406\u89e3 \u300d\u306b\u3064\u3044\u3066\u3001\u8ab0\u3067\u3082\u7406\u89e3\u3067\u304d\u308b\u3088\u3046\u306b\u89e3\u8aac\u3057\u307e\u3059\u3002\u3053\u306e\u8a18\u4e8b\u3092\u8aad\u3081\u3070\u3001\u3042\u306a\u305f\u306e\u60a9\u307f\u304c\u89e3\u6c7a\u3059\u308b\u3060\u3051\u3058\u3083\u306a\u304f\u3001\u65b0\u305f\u306a\u6c17\u4ed8\u304d\u3082\u767a\u898b\u3067\u304d\u308b\u3053\u3068\u3067\u3057\u3087\u3046\u3002\u304a\u60a9\u307f\u306e\u65b9\u306f\u305c\u3072\u3054\u4e00\u8aad\u304f\u3060\u3055\u3044\u3002","og_url":"https:\/\/www.sejuku.net\/blog\/81441","og_site_name":"\u4f8d\u30a8\u30f3\u30b8\u30cb\u30a2\u30d6\u30ed\u30b0","article_publisher":"https:\/\/www.facebook.com\/sejuku2013","article_author":"https:\/\/www.facebook.com\/sejuku2013\/","article_published_time":"2018-11-29T05:46:36+00:00","article_modified_time":"2024-05-06T02:53:38+00:00","og_image":[{"width":700,"height":400,"url":"https:\/\/www.sejuku.net\/blog\/wp-content\/uploads\/2017\/06\/php_eye_new.jpg","type":"image\/jpeg"}],"author":"\u4f8d\u30a8\u30f3\u30b8\u30cb\u30a2\u7de8\u96c6\u90e8","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/samuraijuku","twitter_site":"@samuraijuku","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sejuku.net\/blog\/81441#article","isPartOf":{"@id":"https:\/\/www.sejuku.net\/blog\/81441"},"author":{"name":"\u4f8d\u30a8\u30f3\u30b8\u30cb\u30a2\u7de8\u96c6\u90e8","@id":"https:\/\/www.sejuku.net\/blog\/#\/schema\/person\/e8ca7fd09857a736a25e6b4455a3ab61"},"headline":"PHP\u306e\u30a8\u30e9\u30fc\u30ed\u30b0\u51fa\u529b\u306e\u304a\u60a9\u307f\u3092\u89e3\u6c7a\uff01\u7c21\u5358\u89e3\u8aac\u3067\u6700\u901f\u7406\u89e3","datePublished":"2018-11-29T05:46:36+00:00","dateModified":"2024-05-06T02:53:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sejuku.net\/blog\/81441"},"wordCount":158,"publisher":{"@id":"https:\/\/www.sejuku.net\/blog\/#organization"},"image":{"@id":"https:\/\/www.sejuku.net\/blog\/81441#primaryimage"},"thumbnailUrl":"https:\/\/www.sejuku.net\/blog\/wp-content\/uploads\/2017\/06\/php_eye_new.jpg","articleSection":["PHP\u5b66\u7fd2"],"inLanguage":"ja"},{"@type":"WebPage","@id":"https:\/\/www.sejuku.net\/blog\/81441","url":"https:\/\/www.sejuku.net\/blog\/81441","name":"PHP\u306e\u30a8\u30e9\u30fc\u30ed\u30b0\u51fa\u529b\u306e\u304a\u60a9\u307f\u3092\u89e3\u6c7a\uff01\u7c21\u5358\u89e3\u8aac\u3067\u6700\u901f\u7406\u89e3 | \u4f8d\u30a8\u30f3\u30b8\u30cb\u30a2\u30d6\u30ed\u30b0","isPartOf":{"@id":"https:\/\/www.sejuku.net\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sejuku.net\/blog\/81441#primaryimage"},"image":{"@id":"https:\/\/www.sejuku.net\/blog\/81441#primaryimage"},"thumbnailUrl":"https:\/\/www.sejuku.net\/blog\/wp-content\/uploads\/2017\/06\/php_eye_new.jpg","datePublished":"2018-11-29T05:46:36+00:00","dateModified":"2024-05-06T02:53:38+00:00","description":"\u3053\u306e\u8a18\u4e8b\u3067\u306f\u300c PHP\u306e\u30a8\u30e9\u30fc\u30ed\u30b0\u51fa\u529b\u306e\u304a\u60a9\u307f\u3092\u89e3\u6c7a\uff01\u7c21\u5358\u89e3\u8aac\u3067\u6700\u901f\u7406\u89e3 \u300d\u306b\u3064\u3044\u3066\u3001\u8ab0\u3067\u3082\u7406\u89e3\u3067\u304d\u308b\u3088\u3046\u306b\u89e3\u8aac\u3057\u307e\u3059\u3002\u3053\u306e\u8a18\u4e8b\u3092\u8aad\u3081\u3070\u3001\u3042\u306a\u305f\u306e\u60a9\u307f\u304c\u89e3\u6c7a\u3059\u308b\u3060\u3051\u3058\u3083\u306a\u304f\u3001\u65b0\u305f\u306a\u6c17\u4ed8\u304d\u3082\u767a\u898b\u3067\u304d\u308b\u3053\u3068\u3067\u3057\u3087\u3046\u3002\u304a\u60a9\u307f\u306e\u65b9\u306f\u305c\u3072\u3054\u4e00\u8aad\u304f\u3060\u3055\u3044\u3002","breadcrumb":{"@id":"https:\/\/www.sejuku.net\/blog\/81441#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sejuku.net\/blog\/81441"]}]},{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/www.sejuku.net\/blog\/81441#primaryimage","url":"https:\/\/www.sejuku.net\/blog\/wp-content\/uploads\/2017\/06\/php_eye_new.jpg","contentUrl":"https:\/\/www.sejuku.net\/blog\/wp-content\/uploads\/2017\/06\/php_eye_new.jpg","width":700,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.sejuku.net\/blog\/81441#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sejuku.net\/blog\/"},{"@type":"ListItem","position":2,"name":"PHP\u306e\u30a8\u30e9\u30fc\u30ed\u30b0\u51fa\u529b\u306e\u304a\u60a9\u307f\u3092\u89e3\u6c7a\uff01\u7c21\u5358\u89e3\u8aac\u3067\u6700\u901f\u7406\u89e3"}]},{"@type":"WebSite","@id":"https:\/\/www.sejuku.net\/blog\/#website","url":"https:\/\/www.sejuku.net\/blog\/","name":"\u4f8d\u30a8\u30f3\u30b8\u30cb\u30a2\u30d6\u30ed\u30b0","description":"\u30d7\u30ed\u30b0\u30e9\u30df\u30f3\u30b0\u5b66\u7fd2\u306e\u3059\u3079\u3066\u304c\u30b3\u30b3\u306b\u3002","publisher":{"@id":"https:\/\/www.sejuku.net\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sejuku.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ja"},{"@type":"Organization","@id":"https:\/\/www.sejuku.net\/blog\/#organization","name":"\u682a\u5f0f\u4f1a\u793eSAMURAI","url":"https:\/\/www.sejuku.net\/blog\/","logo":{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/www.sejuku.net\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.sejuku.net\/blog\/wp-content\/uploads\/2023\/07\/logo.png","contentUrl":"https:\/\/www.sejuku.net\/blog\/wp-content\/uploads\/2023\/07\/logo.png","width":600,"height":600,"caption":"\u682a\u5f0f\u4f1a\u793eSAMURAI"},"image":{"@id":"https:\/\/www.sejuku.net\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sejuku2013","https:\/\/x.com\/samuraijuku","https:\/\/www.youtube.com\/channel\/UCCFOQO5aDK0xXam4cUQXT8g\/featured"]},{"@type":"Person","@id":"https:\/\/www.sejuku.net\/blog\/#\/schema\/person\/e8ca7fd09857a736a25e6b4455a3ab61","name":"\u4f8d\u30a8\u30f3\u30b8\u30cb\u30a2\u7de8\u96c6\u90e8","image":{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/secure.gravatar.com\/avatar\/507c280c5c67d2c11fec4fdba20e5bf1ec2fe91f9deb42d2ec50382778b311bf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/507c280c5c67d2c11fec4fdba20e5bf1ec2fe91f9deb42d2ec50382778b311bf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/507c280c5c67d2c11fec4fdba20e5bf1ec2fe91f9deb42d2ec50382778b311bf?s=96&d=mm&r=g","caption":"\u4f8d\u30a8\u30f3\u30b8\u30cb\u30a2\u7de8\u96c6\u90e8"},"description":"\u3010\u30d7\u30ed\u30d5\u30a3\u30fc\u30eb\u3011 DX\u8a8d\u5b9a\u53d6\u5f97\u4e8b\u696d\u8005\u306b\u9078\u5b9a\u3055\u308c\u3066\u3044\u308b\u682a\u5f0f\u4f1a\u793eSAMURAI\u306e\u30de\u30fc\u30b1\u30c6\u30a3\u30f3\u30b0\u30fb\u30b3\u30df\u30e5\u30cb\u30b1\u30fc\u30b7\u30e7\u30f3\u90e8\u304c\u904b\u55b6\u3002\u300c\u8cea\u306e\u9ad8\u3044IT\u6559\u80b2\u3092\u3001\u3059\u3079\u3066\u306e\u4eba\u306b\u300d\u3092\u30df\u30c3\u30b7\u30e7\u30f3\u306b\u3001IT\u30fb\u30d7\u30ed\u30b0\u30e9\u30df\u30f3\u30b0\u3092\u5b66\u3073\u59cb\u3081\u305f\u521d\u5b66\u8005\u306e\u65b9\u306b\u5411\u3051\u8a18\u4e8b\u3092\u57f7\u7b46\u3002 \u7d2f\u8a08\u6307\u5c0e\u8005\u65704\u4e075,000\u540d\u4ee5\u4e0a\u306e\u30d7\u30ed\u30b0\u30e9\u30df\u30f3\u30b0\u30b9\u30af\u30fc\u30eb\u300c\u4f8d\u30a8\u30f3\u30b8\u30cb\u30a2\u300d\u3001\u7d2f\u8a08\u767b\u9332\u8005\u65701\u4e078,000\u4eba\u4ee5\u4e0a\u306e\u30aa\u30f3\u30e9\u30a4\u30f3\u5b66\u7fd2\u30b5\u30fc\u30d3\u30b9\u300c\u4f8d\u30c6\u30e9\u30b3\u30e4\u300d\u3067\u6271\u3046\u6559\u6750\u958b\u767a\u306e\u30ce\u30a6\u30cf\u30a6\u30012013\u5e74\u306e\u5275\u696d\u304b\u3089\u904b\u55b6\u3067\u5f97\u305f\u77e5\u898b\u306b\u57fa\u3065\u304d\u3001\u8a18\u4e8b\u306e\u57f7\u7b46\u3060\u3051\u3067\u306a\u304f\u7de8\u96c6\u30fb\u76e3\u4fee\u3082\u62c5\u5f53\u3057\u3066\u3044\u307e\u3059\u3002 \u3010\u5c02\u9580\u5206\u91ce\u3011 IT\/Web\u958b\u767a\/AI\u30fb\u30ed\u30dc\u30c3\u30c8\u958b\u767a\/\u30a4\u30f3\u30d5\u30e9\u958b\u767a\/\u30b2\u30fc\u30e0\u958b\u767a\/AI\/Web\u30c7\u30b6\u30a4\u30f3","sameAs":["https:\/\/www.sejuku.net\/","https:\/\/www.facebook.com\/sejuku2013\/","https:\/\/www.instagram.com\/samuraiengineer_official\/","https:\/\/x.com\/https:\/\/twitter.com\/samuraijuku","https:\/\/www.youtube.com\/channel\/UCCFOQO5aDK0xXam4cUQXT8g"],"url":"https:\/\/www.sejuku.net\/blog\/author\/samurai-blog"}]}},"_links":{"self":[{"href":"https:\/\/www.sejuku.net\/blog\/wp-json\/wp\/v2\/posts\/81441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sejuku.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sejuku.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sejuku.net\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sejuku.net\/blog\/wp-json\/wp\/v2\/comments?post=81441"}],"version-history":[{"count":0,"href":"https:\/\/www.sejuku.net\/blog\/wp-json\/wp\/v2\/posts\/81441\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sejuku.net\/blog\/wp-json\/wp\/v2\/media\/64982"}],"wp:attachment":[{"href":"https:\/\/www.sejuku.net\/blog\/wp-json\/wp\/v2\/media?parent=81441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sejuku.net\/blog\/wp-json\/wp\/v2\/categories?post=81441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sejuku.net\/blog\/wp-json\/wp\/v2\/tags?post=81441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}